{"id":16036,"date":"2025-05-04T16:42:32","date_gmt":"2025-05-04T14:42:32","guid":{"rendered":"https:\/\/www.a-z-translations.com\/?p=16036"},"modified":"2025-05-04T16:42:36","modified_gmt":"2025-05-04T14:42:36","slug":"es-ist-wieder-soweit","status":"publish","type":"post","link":"https:\/\/www.a-z-translations.com\/es\/es-ist-wieder-soweit\/","title":{"rendered":"Es ist wieder soweit"},"content":{"rendered":"\n<p>Morgen und \u00fcbermorgen sind die schriftlichen Abschlusspr\u00fcfungen an den bayerischen Fachakademien f\u00fcr Sprachen und internationale Kommunikation, die \u00dcbersetzer- und Dolmetscherpr\u00fcfungen, intern kurz \u00dcDP genannt. <\/p>\n\n\n\n<p>Wo ist dieses Jahr nur hin? Eben war doch noch September&#8230;<\/p>\n\n\n\n<p>Wie auch immer, allen Pr\u00fcflingen viel Erfolg und gute Konzentration die n\u00e4chsten beiden Tage!<\/p>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video controls src=\"https:\/\/www.a-z-translations.com\/wp-content\/uploads\/GIF-Viel-Erfolg.mp4\"><\/video><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morgen und \u00fcbermorgen sind die schriftlichen Abschlusspr\u00fcfungen an den bayerischen Fachakademien f\u00fcr Sprachen und internationale Kommunikation, die \u00dcbersetzer- und Dolmetscherpr\u00fcfungen, intern kurz \u00dcDP genannt. Wo ist dieses Jahr nur hin? Eben war doch noch September&#8230; Wie auch immer, allen Pr\u00fcflingen viel Erfolg und gute Konzentration die n\u00e4chsten beiden Tage!<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2454,961,2459,2784],"tags":[2457,92,2817],"class_list":["post-16036","post","type-post","status-publish","format-standard","hentry","category-abschlusspruefungen","category-deutsch","category-fachakademie","category-fachakademie-fuer-sprachen-und-internationale-kommunikation","tag-abschlusspruefungen","tag-deutsch","tag-fachakademie-fuer-sprachen-und-internationale-kommunikation","entry"],"jetpack_publicize_connections":[],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/posts\/16036"}],"collection":[{"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/comments?post=16036"}],"version-history":[{"count":6,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/posts\/16036\/revisions"}],"predecessor-version":[{"id":16045,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/posts\/16036\/revisions\/16045"}],"wp:attachment":[{"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/media?parent=16036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/categories?post=16036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.a-z-translations.com\/es\/wp-json\/wp\/v2\/tags?post=16036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}